{"id":1,"name":"info@websupreme.cz","url":"http:\/\/lugafo.websupreme.cz","description":"","link":"https:\/\/lugafo.websupreme.cz\/index.php\/author\/infowebsupreme-cz\/","slug":"infowebsupreme-cz","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8b610d55ea167d0559322c3e9a80bcd924f732daa6f1c5b804459157d0b13ac2?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8b610d55ea167d0559322c3e9a80bcd924f732daa6f1c5b804459157d0b13ac2?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8b610d55ea167d0559322c3e9a80bcd924f732daa6f1c5b804459157d0b13ac2?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/lugafo.websupreme.cz\/index.php\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lugafo.websupreme.cz\/index.php\/wp-json\/wp\/v2\/users"}]}}